{"id":1842,"date":"2024-06-04T22:47:01","date_gmt":"2024-06-05T03:47:01","guid":{"rendered":"https:\/\/www.mydental.local\/?p=1842"},"modified":"2024-06-11T22:49:42","modified_gmt":"2024-06-12T03:49:42","slug":"hablar-de-dientes-que-es-un-absceso-dental","status":"publish","type":"post","link":"https:\/\/www.mydental.com\/es\/tooth-talk-what-is-an-abscessed-tooth\/","title":{"rendered":"Charla dental: \u00bfQu\u00e9 es un absceso dental?"},"content":{"rendered":"<p>\u00bfSientes un fuerte dolor de muelas en la boca y no se te quita? Si el dolor se vuelve insoportable e incluso ves hinchaz\u00f3n en la zona afectada, es posible que tengas un absceso dental.<\/p>\n\n\n\n<p>Un absceso dental no solo es bastante doloroso, sino que puede ser un grave problema de salud si no se trata. Si cree que tiene una infecci\u00f3n, es fundamental buscar atenci\u00f3n dental lo antes posible. Puede preguntarle al dentista: \u00bfqu\u00e9 es un absceso dental? Y tambi\u00e9n obtener m\u00e1s informaci\u00f3n sobre el plan de tratamiento ideal para aliviar el dolor y recuperar su salud dental.<\/p>\n\n\n\n<p>En este art\u00edculo, cubriremos todo lo que necesita saber sobre un absceso dental. Adem\u00e1s de identificar los s\u00edntomas si padece esta afecci\u00f3n, es igualmente importante asegurarse de recibir el mejor tratamiento dental lo antes posible.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es un diente abscesado?<\/h2>\n\n\n\n<p>Cuando tienes un absceso dental, significa que tienes una infecci\u00f3n en la boca. Generalmente, la infecci\u00f3n comienza en la ra\u00edz del diente o en el espacio entre los dientes y las enc\u00edas. Las bacterias comienzan a invadir la zona y el sistema inmunitario del cuerpo se activa para combatir la infecci\u00f3n. Como resultado, se forma una bolsa de pus.<\/p>\n\n\n\n<p>Cuando la infecci\u00f3n llega al punto de formar un absceso, es necesaria una intervenci\u00f3n dental o m\u00e9dica. La presencia de esta bolsa de infecci\u00f3n significa que el sistema inmunitario no puede combatirla eficazmente. Si la infecci\u00f3n no se trata, comenzar\u00e1 a propagarse a los tejidos y dientes circundantes. Con el tiempo, puede llegar al torrente sangu\u00edneo y causar problemas de salud sist\u00e9micos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Existen dos tipos diferentes de abscesos dentales:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Absceso periapical: Este tipo de absceso dental se forma en la ra\u00edz del diente. Generalmente se localiza en la punta, el punto m\u00e1s profundo de la enc\u00eda.<\/li>\n\n\n\n<li>Absceso Periodontal: Si tienes este tipo de absceso, entonces es una infecci\u00f3n que se forma en las enc\u00edas ubicadas al lado de la ra\u00edz del diente.<\/li>\n<\/ul>\n\n\n\n<p>Independientemente de la ubicaci\u00f3n, es necesario visitar a un dentista para eliminar la infecci\u00f3n y prevenir complicaciones m\u00e1s graves.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las causas m\u00e1s comunes de los abscesos dentales<\/h2>\n\n\n\n<p>\u00bfPor qu\u00e9 tiene un absceso dental? Si bien la presencia de bacterias es la causa del desarrollo y la progresi\u00f3n de la infecci\u00f3n, a menudo existen causas subyacentes que permiten que las bacterias accedan a la ra\u00edz del diente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Algunas de las causas m\u00e1s comunes de abscesos dentales incluyen:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Caries: El esmalte protector del diente se ha visto da\u00f1ado por las caries causadas por bacterias en la boca. A medida que la caries progresa, se desplaza desde la superficie del diente hacia las zonas m\u00e1s profundas. Si esta infecci\u00f3n alcanza la parte interna donde se encuentran los vasos sangu\u00edneos y los nervios (conocida como pulpa), puede provocar un dolor de muelas grave y un absceso.<\/li>\n\n\n\n<li>Enfermedad de las enc\u00edas: A medida que la enfermedad de las enc\u00edas progresa, las enc\u00edas se separan de los dientes. Como resultado, se pueden formar bolsas de infecci\u00f3n donde las bacterias quedan atrapadas bajo la l\u00ednea de las enc\u00edas. La infecci\u00f3n puede empeorar con el tiempo y formar un absceso.<\/li>\n\n\n\n<li>Astillado o grieta en el diente: Quiz\u00e1s mordiste algo duro o el diente se ha debilitado por el desgaste de los a\u00f1os. Es posible que se forme un astillado o grieta en el diente, lo que puede ser una puerta de entrada para las bacterias.<\/li>\n\n\n\n<li>Traumatismo: Cualquier da\u00f1o o lesi\u00f3n en la boca puede aumentar la probabilidad de formaci\u00f3n de un absceso. Por ejemplo, si recibe un golpe en la boca durante una actividad deportiva y se da\u00f1a un diente, las bacterias podr\u00edan desplazarse a la zona da\u00f1ada y causar una infecci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo s\u00e9 si mi diente tiene un absceso?<\/h2>\n\n\n\n<p>Aunque un dentista puede dar un diagn\u00f3stico oficial de un absceso, es importante que todos conozcan los s\u00edntomas m\u00e1s comunes. Se puede buscar en l\u00ednea qu\u00e9 es un absceso dental. Sin embargo, los s\u00edntomas suelen ser bastante claros y sencillos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los s\u00edntomas m\u00e1s comunes de un absceso dental incluyen:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dolor de muelas severo que no cede<\/li>\n\n\n\n<li>Hinchaz\u00f3n en la mand\u00edbula y\/o la cara<\/li>\n\n\n\n<li>Sensibilidad cuando el diente entra en contacto con el fr\u00edo o el calor.<\/li>\n\n\n\n<li>Fiebre<\/li>\n\n\n\n<li>Mal sabor de boca<\/li>\n\n\n\n<li>Mal aliento<\/li>\n\n\n\n<li>Dificultad para tragar<\/li>\n<\/ul>\n\n\n\n<p>\u00bfC\u00f3mo se ve un absceso dental? La mayor\u00eda de los pacientes pueden sentir los s\u00edntomas incluso si no hay s\u00edntomas visibles. Por ejemplo, podr\u00eda tener un dolor de muelas intenso, pero una inspecci\u00f3n visual del diente parece normal. O bien, algunos pacientes presentan signos visibles de la infecci\u00f3n, como hinchaz\u00f3n y una bolsa de pus visible en la zona infectada.<\/p>\n\n\n\n<p>\u00bfCu\u00e1l es la diferencia entre un diente infectado y un absceso dental? Lo cierto es que ambos t\u00e9rminos se refieren al mismo tipo de problema dental. Si tienes un absceso dental, significa que hay una infecci\u00f3n en el diente.<\/p>\n\n\n\n<p>Si sospecha que tiene una infecci\u00f3n dental, lo mejor es contactar con nuestra cl\u00ednica dental para una evaluaci\u00f3n. Examinaremos su diente y le ayudaremos a determinar un diagn\u00f3stico preciso y el plan de tratamiento necesario.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1les son los primeros signos de sepsis por absceso dental?<\/h2>\n\n\n\n<p>Aunque no es com\u00fan, existe la posibilidad de que la infecci\u00f3n dental se propague al torrente sangu\u00edneo y cause una afecci\u00f3n conocida como sepsis. Esta infecci\u00f3n sist\u00e9mica puede causar graves problemas de salud y requiere atenci\u00f3n m\u00e9dica de emergencia inmediata.<\/p>\n\n\n\n<p>Los signos de sepsis incluyen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fiebre alta<\/li>\n\n\n\n<li>Temblores y escalofr\u00edos<\/li>\n\n\n\n<li>Aumento de la frecuencia card\u00edaca<\/li>\n\n\n\n<li>Malestar o dolor extremo<\/li>\n\n\n\n<li>La piel est\u00e1 sudorosa o h\u00fameda<\/li>\n\n\n\n<li>Cambios en la respiraci\u00f3n (ya sea dificultad para respirar o respiraci\u00f3n r\u00e1pida)<\/li>\n\n\n\n<li>Desorientaci\u00f3n o confusi\u00f3n<\/li>\n<\/ul>\n\n\n\n<p>Si nota alguno de estos s\u00edntomas, es esencial buscar intervenci\u00f3n m\u00e9dica de emergencia sin demora.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo se arregla un absceso dental?<\/h2>\n\n\n\n<p>Existen varias opciones de tratamiento, seg\u00fan la gravedad de la infecci\u00f3n y el grado de afectaci\u00f3n del diente. Cada paciente es \u00fanico, por lo que es recomendable consultar con un dentista experimentado para determinar el plan de tratamiento ideal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los tratamientos m\u00e1s comunes para el absceso dental incluyen:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Endodoncia: Este tratamiento consiste en perforar el diente para que el dentista pueda extraer la pulpa interna y limpiar la infecci\u00f3n. La buena noticia es que la tecnolog\u00eda de endodoncia ha avanzado mucho en los \u00faltimos a\u00f1os, haci\u00e9ndolo tan c\u00f3modo como un empaste normal. Una endodoncia suele ser una soluci\u00f3n eficaz para evitar la extracci\u00f3n del diente.<\/li>\n\n\n\n<li>Extracci\u00f3n dental: Si la infecci\u00f3n es grave y el diente est\u00e1 da\u00f1ado sin posibilidad de reparaci\u00f3n, el dentista podr\u00eda recomendar una extracci\u00f3n. Si bien nuestro objetivo es salvar el diente natural siempre que sea posible, en ocasiones la extracci\u00f3n es la mejor opci\u00f3n.<\/li>\n\n\n\n<li>Antibi\u00f3ticos: A veces, no basta con eliminar la parte infectada del diente. El dentista podr\u00eda recomendar un tratamiento con antibi\u00f3ticos para combatir las bacterias que puedan quedar. Los antibi\u00f3ticos pueden administrarse mediante una pastilla, terapia intravenosa o un tratamiento local mediante la aplicaci\u00f3n de antibi\u00f3ticos en el interior del diente.<\/li>\n\n\n\n<li>Manejo del dolor: Adem\u00e1s de abordar la causa del absceso dental, consulte con su dentista sobre las opciones para el manejo del dolor. Estas pueden incluir analg\u00e9sicos o el uso de compresas fr\u00edas para controlar la inflamaci\u00f3n y reducir el dolor.<\/li>\n<\/ul>\n\n\n\n<p>\u00bfLos antibi\u00f3ticos eliminan un absceso dental? S\u00ed, pueden ser una parte importante del plan de tratamiento. Sin embargo, es importante tener en cuenta que los antibi\u00f3ticos por s\u00ed solos no son suficientes. Tambi\u00e9n es necesario que el dentista trate la causa subyacente o el da\u00f1o al diente para evitar que la infecci\u00f3n reaparezca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Llame a los expertos dentales locales<\/h2>\n\n\n\n<p>Si bien puede encontrar informaci\u00f3n en l\u00ednea sobre qu\u00e9 es un absceso dental, lo m\u00e1s importante es contactar a un dentista lo antes posible. Nuestro equipo est\u00e1 aqu\u00ed para ayudarle si tiene un absceso dental. Contacte con myDental para programar una cita en uno de nuestros dentistas cercanos. <a href=\"https:\/\/www.mydental.com\/es\/lugares\/\"><u>ubicaciones<\/u><\/a>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Is your mouth throbbing and you have a toothache that won&#8217;t go away? If the pain is becoming unbearable and you even see swelling in the affected area, then you might be dealing with an abscessed tooth. Not only is a tooth abscess quite painful, it can be a serious health concern when left untreated. [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/www.mydental.com\/es\/tooth-talk-what-is-an-abscessed-tooth\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":1843,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[62],"tags":[],"blog_services":[52],"class_list":["post-1842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dental-emergencies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>What Is an Abscessed Tooth? Causes and Treatment | myDental<\/title>\n<meta name=\"description\" content=\"An abscessed tooth is a painful infection at the root. Learn what causes dental abscesses, the symptoms to watch for, and available treatment options.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mydental.com\/es\/hablar-de-dientes-que-es-un-absceso-dental\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What Is an Abscessed Tooth? Causes and Treatment | myDental\" \/>\n<meta property=\"og:description\" content=\"An abscessed tooth is a painful infection at the root. Learn what causes dental abscesses, the symptoms to watch for, and available treatment options.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mydental.com\/es\/hablar-de-dientes-que-es-un-absceso-dental\/\" \/>\n<meta property=\"og:site_name\" content=\"myDental\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-05T03:47:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T03:49:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mydental.com\/wp-content\/uploads\/2024\/06\/myDental.com-Tooth-Talk-What-is-an-Abscessed-Tooth.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1050\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"myDental Blogger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"myDental Blogger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/\"},\"author\":{\"name\":\"myDental Blogger\",\"@id\":\"https:\\\/\\\/www.mydental.com\\\/#\\\/schema\\\/person\\\/c530cd567ebf01f6566eea2f660caae4\"},\"headline\":\"Tooth Talk: What is an Abscessed Tooth?\",\"datePublished\":\"2024-06-05T03:47:01+00:00\",\"dateModified\":\"2024-06-12T03:49:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/\"},\"wordCount\":1372,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mydental.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mydental.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/myDental.com-Tooth-Talk-What-is-an-Abscessed-Tooth.jpeg\",\"articleSection\":[\"Dental Emergencies\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/\",\"url\":\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/\",\"name\":\"What Is an Abscessed Tooth? Causes and Treatment | myDental\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mydental.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mydental.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/myDental.com-Tooth-Talk-What-is-an-Abscessed-Tooth.jpeg\",\"datePublished\":\"2024-06-05T03:47:01+00:00\",\"dateModified\":\"2024-06-12T03:49:42+00:00\",\"description\":\"An abscessed tooth is a painful infection at the root. Learn what causes dental abscesses, the symptoms to watch for, and available treatment options.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mydental.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/myDental.com-Tooth-Talk-What-is-an-Abscessed-Tooth.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.mydental.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/myDental.com-Tooth-Talk-What-is-an-Abscessed-Tooth.jpeg\",\"width\":1500,\"height\":1050},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mydental.com\\\/tooth-talk-what-is-an-abscessed-tooth\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mydental.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tooth Talk: What is an Abscessed Tooth?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mydental.com\\\/#website\",\"url\":\"https:\\\/\\\/www.mydental.com\\\/\",\"name\":\"myDental\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mydental.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mydental.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mydental.com\\\/#organization\",\"name\":\"myDental\",\"url\":\"https:\\\/\\\/www.mydental.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mydental.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mydental.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-myDental-logo-r.png\",\"contentUrl\":\"https:\\\/\\\/www.mydental.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-myDental-logo-r.png\",\"width\":762,\"height\":139,\"caption\":\"myDental\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mydental.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mydental.com\\\/#\\\/schema\\\/person\\\/c530cd567ebf01f6566eea2f660caae4\",\"name\":\"myDental Blogger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aeb792cfc11e2c3d0f1fa24e814ad7429f7ebfc67ba0a7e2bbe1b61c35497e9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aeb792cfc11e2c3d0f1fa24e814ad7429f7ebfc67ba0a7e2bbe1b61c35497e9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aeb792cfc11e2c3d0f1fa24e814ad7429f7ebfc67ba0a7e2bbe1b61c35497e9b?s=96&d=mm&r=g\",\"caption\":\"myDental Blogger\"},\"url\":\"https:\\\/\\\/www.mydental.com\\\/es\\\/author\\\/blogger\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es un absceso dental? Causas y tratamiento | myDental","description":"Un absceso dental es una infecci\u00f3n dolorosa de ra\u00edz. Conozca las causas de los abscesos dentales, los s\u00edntomas a los que debe prestar atenci\u00f3n y las opciones de tratamiento disponibles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mydental.com\/es\/hablar-de-dientes-que-es-un-absceso-dental\/","og_locale":"es_MX","og_type":"article","og_title":"What Is an Abscessed Tooth? Causes and Treatment | myDental","og_description":"An abscessed tooth is a painful infection at the root. Learn what causes dental abscesses, the symptoms to watch for, and available treatment options.","og_url":"https:\/\/www.mydental.com\/es\/hablar-de-dientes-que-es-un-absceso-dental\/","og_site_name":"myDental","article_published_time":"2024-06-05T03:47:01+00:00","article_modified_time":"2024-06-12T03:49:42+00:00","og_image":[{"width":1500,"height":1050,"url":"https:\/\/www.mydental.com\/wp-content\/uploads\/2024\/06\/myDental.com-Tooth-Talk-What-is-an-Abscessed-Tooth.jpeg","type":"image\/jpeg"}],"author":"myDental Blogger","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"myDental Blogger","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/#article","isPartOf":{"@id":"https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/"},"author":{"name":"myDental Blogger","@id":"https:\/\/www.mydental.com\/#\/schema\/person\/c530cd567ebf01f6566eea2f660caae4"},"headline":"Tooth Talk: What is an Abscessed Tooth?","datePublished":"2024-06-05T03:47:01+00:00","dateModified":"2024-06-12T03:49:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/"},"wordCount":1372,"publisher":{"@id":"https:\/\/www.mydental.com\/#organization"},"image":{"@id":"https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mydental.com\/wp-content\/uploads\/2024\/06\/myDental.com-Tooth-Talk-What-is-an-Abscessed-Tooth.jpeg","articleSection":["Dental Emergencies"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/","url":"https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/","name":"\u00bfQu\u00e9 es un absceso dental? Causas y tratamiento | myDental","isPartOf":{"@id":"https:\/\/www.mydental.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/#primaryimage"},"image":{"@id":"https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mydental.com\/wp-content\/uploads\/2024\/06\/myDental.com-Tooth-Talk-What-is-an-Abscessed-Tooth.jpeg","datePublished":"2024-06-05T03:47:01+00:00","dateModified":"2024-06-12T03:49:42+00:00","description":"Un absceso dental es una infecci\u00f3n dolorosa de ra\u00edz. Conozca las causas de los abscesos dentales, los s\u00edntomas a los que debe prestar atenci\u00f3n y las opciones de tratamiento disponibles.","breadcrumb":{"@id":"https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/#primaryimage","url":"https:\/\/www.mydental.com\/wp-content\/uploads\/2024\/06\/myDental.com-Tooth-Talk-What-is-an-Abscessed-Tooth.jpeg","contentUrl":"https:\/\/www.mydental.com\/wp-content\/uploads\/2024\/06\/myDental.com-Tooth-Talk-What-is-an-Abscessed-Tooth.jpeg","width":1500,"height":1050},{"@type":"BreadcrumbList","@id":"https:\/\/www.mydental.com\/tooth-talk-what-is-an-abscessed-tooth\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mydental.com\/"},{"@type":"ListItem","position":2,"name":"Tooth Talk: What is an Abscessed Tooth?"}]},{"@type":"WebSite","@id":"https:\/\/www.mydental.com\/#website","url":"https:\/\/www.mydental.com\/","name":"miDental","description":"","publisher":{"@id":"https:\/\/www.mydental.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mydental.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mydental.com\/#organization","name":"miDental","url":"https:\/\/www.mydental.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mydental.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.mydental.com\/wp-content\/uploads\/2024\/05\/cropped-myDental-logo-r.png","contentUrl":"https:\/\/www.mydental.com\/wp-content\/uploads\/2024\/05\/cropped-myDental-logo-r.png","width":762,"height":139,"caption":"myDental"},"image":{"@id":"https:\/\/www.mydental.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mydental.com\/#\/schema\/person\/c530cd567ebf01f6566eea2f660caae4","name":"Blogger de myDental","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/aeb792cfc11e2c3d0f1fa24e814ad7429f7ebfc67ba0a7e2bbe1b61c35497e9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aeb792cfc11e2c3d0f1fa24e814ad7429f7ebfc67ba0a7e2bbe1b61c35497e9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aeb792cfc11e2c3d0f1fa24e814ad7429f7ebfc67ba0a7e2bbe1b61c35497e9b?s=96&d=mm&r=g","caption":"myDental Blogger"},"url":"https:\/\/www.mydental.com\/es\/author\/blogger\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/posts\/1842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/comments?post=1842"}],"version-history":[{"count":1,"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/posts\/1842\/revisions"}],"predecessor-version":[{"id":1844,"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/posts\/1842\/revisions\/1844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/media\/1843"}],"wp:attachment":[{"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/media?parent=1842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/categories?post=1842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/tags?post=1842"},{"taxonomy":"blog_services","embeddable":true,"href":"https:\/\/www.mydental.com\/es\/wp-json\/wp\/v2\/blog_services?post=1842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}